{"id":1069,"date":"2017-06-20T10:19:56","date_gmt":"2017-06-20T08:19:56","guid":{"rendered":"http:\/\/www.shopiemonte.com\/blog\/?p=1069"},"modified":"2017-06-20T10:20:40","modified_gmt":"2017-06-20T08:20:40","slug":"micro-birrifici-in-piemonte-intervista-a-civale","status":"publish","type":"post","link":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale","title":{"rendered":"Micro birrifici in Piemonte: intervista a Civale"},"content":{"rendered":"<p>Il Piemonte non \u00e8 pi\u00f9 solo vino, ma anche birra artigianale. Questo mese abbiamo deciso di intervistare il <strong>micro <a href=\"http:\/\/www.stage.shopiemonte.com\/manufacturers\/birrificio-civale-36\/\" target=\"_blank\" rel=\"noopener noreferrer\">birrificio Civale<\/a><\/strong> di Spinetta Marengo in provincia di <strong>Alessandria<\/strong>, una piccola azienda che\u00a0si contraddistingue per la passione, la ricercatezza e per la qualit\u00e0 delle sue produzione (tutta made in Italy!), ecco cosa ci hanno raccontato!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Siamo curiosi: come \u00e8 nata l\u2019idea del vostro micro birrificio, e quanto questo \u00e8 legato al Piemonte e al vostro territorio?<\/strong><\/p>\n<p>Due passioni si sono unite la mia (Vincenzo Civale) e quella di Daniele..entrambi arrivavamo da esperienze da\u00a0homebrewers e confrontandoci abbiamo deciso di intraprendere insieme il grande viaggio imprenditoriale nel mondo\u00a0della birra aritigianale.<br \/>\nIl Piemonte \u00e8 luogo in cui viviamo e sicuramente da dove siamo partiti per ideare le nostre birre: per le nostre creazioni abbiamo deciso di usare\u00a0i prodotti proveniente della nostre zone: ad esempio le\u00a0erbe e spezie per <a href=\"http:\/\/www.stage.shopiemonte.com\/monflowers-birra-bianca-75cl-477-477\" target=\"_blank\" rel=\"noopener noreferrer\">la nostra blanche Monflowers<\/a>, oppure \u00a0il miele da acacia nostrano per la <a href=\"http:\/\/www.stage.shopiemonte.com\/punto-di-fuga-75cl-483-483\" target=\"_blank\" rel=\"noopener noreferrer\">Punto di fuga<\/a>\u00a0e le\u00a0amarene per la <strong>Amaris&#8230;<\/strong>\u00a0in futuro aspettatevi altre novit\u00e0 a km0!<\/p>\n<p><strong>L\u2019italia \u00e8 un paese tradizionalmente produttore di vino, ma in questi anni le birre, soprattutto quelle artigianali, stanno crescendo molto, appassionando sempre pi\u00f9 persone grazie a prodotti di alta qualit\u00e0, come vedete voi il futuro della birra nel nostro paese?C\u2019\u00e8 ancora margine di crescita?<\/strong><\/p>\n<p>La genialita e la creativita&#8217; italiana stanno favorendo la esplosione del fenomeno &#8220;birra artigianale&#8221;\u00a0i piccoli produttori come noi, purtroppo per\u00f2, spesso si trovano spaventati e bloccati dai tanti\u00a0meccanismi burocratici della nostra Pubblica Amministrazione.<br \/>\nSicuramente c&#8217;\u00e8 ancora margine per questo settore, ma solo per i birrifici che garantiscono una elavata e costante qualit\u00e0 nelle loro produzioni.<\/p>\n<p><strong>Estate, tempo di rinfrescarsi! Vogliamo sapere qual \u00e8 la top 3 delle vostre birre preferite e perch\u00e9.<\/strong><\/p>\n<p>La prima \u00e8 sicuramente la nostra <strong><a href=\"http:\/\/www.stage.shopiemonte.com\/lumina-birra-bionda-75cl-479-479\" target=\"_blank\" rel=\"noopener noreferrer\">Lumina<\/a><\/strong>:\u00a0fresca, dissetante e con un giusto amaro, perfetta per i mesi pi\u00f9 caldi!<br \/>\nLa seconda la\u00a0<strong><a href=\"http:\/\/www.stage.shopiemonte.com\/monflowers-birra-bianca-75cl-477-477\" target=\"_blank\" rel=\"noopener noreferrer\">Monflowers<\/a><\/strong>: una blanche che ci riporta ai profumi dei campi del Monferrato, lo scoprirete anche voi ad ogni sorso!<br \/>\nAl terzo posto scegliamo la\u00a0<strong><a href=\"http:\/\/www.stage.shopiemonte.com\/punto-di-fuga-75cl-483-483\" target=\"_blank\" rel=\"noopener noreferrer\">Punto di Fuga<\/a><\/strong>: una birra dalle note olfattive che derivano dalle\u00a0resine del miele d&#8217;acacia e dai luppoli del pacifico rendendola\u00a0inebriante e beverina, nonostante il grado alcolico importante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri l&#8217;intervista a Civale, uno dei migliori micro birrifici del Piemonte e scopri la loro storia e la loro passione per le birre artigianali!<\/p>\n","protected":false},"author":3,"featured_media":1135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-storie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Micro birrifici in Piemonte: intervista a Civale - Il Magazine di Shopiemonte<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;intervista a Civale, uno dei migliori micro birrifici del Piemonte e scopri la loro storia e la loro passione per le birre artigianali\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Micro birrifici in Piemonte: intervista a Civale - Il Magazine di Shopiemonte\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;intervista a Civale, uno dei migliori micro birrifici del Piemonte e scopri la loro storia e la loro passione per le birre artigianali\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale\" \/>\n<meta property=\"og:site_name\" content=\"Il Magazine di Shopiemonte\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-20T08:19:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-20T08:20:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2017\/06\/311618_417082465009417_514012254_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valentina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale\",\"url\":\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale\",\"name\":\"Micro birrifici in Piemonte: intervista a Civale - Il Magazine di Shopiemonte\",\"isPartOf\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2017\/06\/311618_417082465009417_514012254_n.jpg\",\"datePublished\":\"2017-06-20T08:19:56+00:00\",\"dateModified\":\"2017-06-20T08:20:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/e487e1e6d293d11bf7614d815d33e0aa\"},\"description\":\"Scopri l'intervista a Civale, uno dei migliori micro birrifici del Piemonte e scopri la loro storia e la loro passione per le birre artigianali\",\"breadcrumb\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#primaryimage\",\"url\":\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2017\/06\/311618_417082465009417_514012254_n.jpg\",\"contentUrl\":\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2017\/06\/311618_417082465009417_514012254_n.jpg\",\"width\":720,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.shopiemonte.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Storie\",\"item\":\"https:\/\/www.shopiemonte.com\/blog\/category\/storie\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Micro birrifici in Piemonte: intervista a Civale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#website\",\"url\":\"https:\/\/www.shopiemonte.com\/blog\/\",\"name\":\"Il Magazine di Shopiemonte\",\"description\":\"ricette e curiosit\u00e0 dal Piemonte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.shopiemonte.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/e487e1e6d293d11bf7614d815d33e0aa\",\"name\":\"Valentina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b9b33c12ff563859ecf814db6058ca83?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b9b33c12ff563859ecf814db6058ca83?s=96&d=mm&r=g\",\"caption\":\"Valentina\"},\"sameAs\":[\"https:\/\/cucinaecantina.net\/\"],\"url\":\"https:\/\/www.shopiemonte.com\/blog\/author\/valentina\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Micro birrifici in Piemonte: intervista a Civale - Il Magazine di Shopiemonte","description":"Scopri l'intervista a Civale, uno dei migliori micro birrifici del Piemonte e scopri la loro storia e la loro passione per le birre artigianali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale","og_locale":"it_IT","og_type":"article","og_title":"Micro birrifici in Piemonte: intervista a Civale - Il Magazine di Shopiemonte","og_description":"Scopri l'intervista a Civale, uno dei migliori micro birrifici del Piemonte e scopri la loro storia e la loro passione per le birre artigianali","og_url":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale","og_site_name":"Il Magazine di Shopiemonte","article_published_time":"2017-06-20T08:19:56+00:00","article_modified_time":"2017-06-20T08:20:40+00:00","og_image":[{"width":720,"height":478,"url":"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2017\/06\/311618_417082465009417_514012254_n.jpg","type":"image\/jpeg"}],"author":"Valentina","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Valentina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale","url":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale","name":"Micro birrifici in Piemonte: intervista a Civale - Il Magazine di Shopiemonte","isPartOf":{"@id":"https:\/\/www.shopiemonte.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#primaryimage"},"image":{"@id":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#primaryimage"},"thumbnailUrl":"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2017\/06\/311618_417082465009417_514012254_n.jpg","datePublished":"2017-06-20T08:19:56+00:00","dateModified":"2017-06-20T08:20:40+00:00","author":{"@id":"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/e487e1e6d293d11bf7614d815d33e0aa"},"description":"Scopri l'intervista a Civale, uno dei migliori micro birrifici del Piemonte e scopri la loro storia e la loro passione per le birre artigianali","breadcrumb":{"@id":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#primaryimage","url":"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2017\/06\/311618_417082465009417_514012254_n.jpg","contentUrl":"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2017\/06\/311618_417082465009417_514012254_n.jpg","width":720,"height":478},{"@type":"BreadcrumbList","@id":"https:\/\/www.shopiemonte.com\/blog\/storie\/micro-birrifici-in-piemonte-intervista-a-civale#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shopiemonte.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Storie","item":"https:\/\/www.shopiemonte.com\/blog\/category\/storie"},{"@type":"ListItem","position":3,"name":"Micro birrifici in Piemonte: intervista a Civale"}]},{"@type":"WebSite","@id":"https:\/\/www.shopiemonte.com\/blog\/#website","url":"https:\/\/www.shopiemonte.com\/blog\/","name":"Il Magazine di Shopiemonte","description":"ricette e curiosit\u00e0 dal Piemonte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shopiemonte.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/e487e1e6d293d11bf7614d815d33e0aa","name":"Valentina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b9b33c12ff563859ecf814db6058ca83?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9b33c12ff563859ecf814db6058ca83?s=96&d=mm&r=g","caption":"Valentina"},"sameAs":["https:\/\/cucinaecantina.net\/"],"url":"https:\/\/www.shopiemonte.com\/blog\/author\/valentina"}]}},"_links":{"self":[{"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/posts\/1069"}],"collection":[{"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/comments?post=1069"}],"version-history":[{"count":0,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/posts\/1069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/media\/1135"}],"wp:attachment":[{"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/media?parent=1069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/categories?post=1069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/tags?post=1069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}