{"id":1769,"date":"2022-02-09T14:59:00","date_gmt":"2022-02-09T13:59:00","guid":{"rendered":"https:\/\/www.shopiemonte.com\/blog\/?p=1769"},"modified":"2022-02-11T12:13:56","modified_gmt":"2022-02-11T11:13:56","slug":"maschere-carnevale-pasta-frolla","status":"publish","type":"post","link":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla","title":{"rendered":"Maschere di Carnevale di Pasta Frolla"},"content":{"rendered":"<p>Per Carnevale i dolci pi\u00f9 preparati solitamente sono: le <em>bugie<\/em> (o <em>chiacchiere<\/em>), i <em>frici\u00f2<\/em>, <em>cenci al vin santo<\/em>, <em>castagnole<\/em> e molti altri, ma questa volta volevamo realizzare qualcosa di diverso e che avesse a che fare con la pasta frolla: visto il periodo, abbiamo ritagliato delle <strong>maschere di pasta frolla<\/strong> e le abbiamo decorate con cioccolato al latte e granelle colorate! Ed ecco le nostre <strong>Maschere di Carnevale di Pasta Frolla<\/strong>!<\/p>\n<p>Questa ricetta \u00e8 semplicissima e ci si pu\u00f2 avvalere dell&#8217;aiuto dei pi\u00f9 piccoli per divertirsi in cucina. <strong>Cucinare con i bambini pu\u00f2 essere divertente<\/strong> e soprattutto <strong>molto educativo<\/strong> per loro, possono imparare a preparare qualcosa con le loro manine e collaborare con noi.<\/p>\n<blockquote><p>Vi siete mai chiesti perch\u00e8 ci si maschera a Carnevale? L&#8217;usanza ha radici antichissime e si trova in molte parti del mondo, etnie e culture differenti. La sostanza \u00e8 per\u00f2 sempre la stessa: la perdita di identit\u00e0 da parte di chi la indossa. Quindi in questa festivit\u00e0 mascheriamoci e sentiamoci chi solitamente non siamo o non possiamo essere: un gatto, un supereroe, una principessa, un albero, o&#8230; una <em><strong>maschera di pasta frolla<\/strong><\/em>!<\/p><\/blockquote>\n<p>Se ami mettere le <em>mani in pasta<\/em>, la nostra <a href=\"https:\/\/www.shopiemonte.com\/farina\" target=\"_blank\" rel=\"noopener\"><strong>selezione di farine macinate a pietra<\/strong><\/a>, <strong>genuine<\/strong>, <strong>biologiche<\/strong> e <strong>integrali<\/strong> ti ispirer\u00e0 nella creazione di nuove ricette!<\/p>\n\t\r\n\t<div class=\"wrapper-penci-recipe\">\r\n\t\t<div class=\"penci-recipe\" id=\"printrepcipe4634\" itemscope itemtype=\"http:\/\/schema.org\/Recipe\">\r\n\t\t\t<div class=\"penci-recipe-heading\">\r\n\t\t\t\t\t\t\t\t\t<h2 itemprop=\"name\">Maschere di Carnevale di Pasta Frolla<\/h2>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" style=\"display: none !important;\" itemprop=\"image\" src=\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-pasta-frolla-150x150.jpg\" width=\"50\" height=\"50\"\/>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"penci-recipe-print\" data-print=\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/plugins\/penci-recipe\/inc\/print.css\"><i class=\"fa fa-print\"><\/i> Print This<\/a>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"penci-recipe-meta\">\r\n\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t<i class=\"fa fa-user\"><\/i> Serves: <span class=\"servings\" itemprop=\"recipeYield\">8 maschere<\/span>\r\n\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t<i class=\"fa fa-clock-o\"><\/i> Prep Time: <time itemprop=\"prepTime\">30 min<\/time>\r\n\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t<i class=\"fa fa-clock-o\"><\/i> Cooking Time: <time itemprop=\"cookTime\">10-12 min<\/time>\r\n\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<div class=\"penci-recipe-ingredients\">\r\n\t\t\t\t\t<h3 class=\"penci-recipe-title\">Ingredients<\/h3>\r\n\t\t\t\t\t<ul>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span itemprop=\"recipeIngredient\">150g di burro<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span itemprop=\"recipeIngredient\">125g di zucchero<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span itemprop=\"recipeIngredient\">1 uovo<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span itemprop=\"recipeIngredient\">1 bustina di lievito per dolci<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span itemprop=\"recipeIngredient\">1 barretta di Cioccolato al Latte di Pastiglie Leone<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span itemprop=\"recipeIngredient\">zuccherini colorati<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span itemprop=\"recipeIngredient\">300g di Farina per Frolla di Farina Viva<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"penci-recipe-method\" itemprop=\"recipeInstructions\">\r\n\t\t\t\t\t<h3 class=\"penci-recipe-title\">Instructions<\/h3>\r\n\t\t\t\t\t<p>Con le fruste elettriche montate il burro a temperatura ambiente e lo zucchero, poi aggiungete l&#8217;uovo, la farina con la bustina di lievito, lavorate il composto a mano fino a far amalgamare bene gli ingredienti.<\/p>\n<p>Ora l&#8217;impasto ha bisogno di riposare in frigo per 30 minuti, dopo di che potete stenderlo con uno spessore di circa 3mm e cominciare a realizzare le maschere, aiutandovi come linee guida con delle maschere pre-ritagliate da fogli di carta, con le forme che preferite. Noi abbiamo fatto le classiche.<\/p>\n<p>Potete infornare a 180\u00b0 per circa 10-12 minuti controllando che le maschere possano dorarsi appena.<\/p>\n<p>Intanto che attendete di cuocerle tutte e che si siano raffreddate, preparatevi per la decorazione: quindi sciogliete appena la barretta di cioccolato al Latte in un pentolino e prendete gli zuccherini colorati.<\/p>\n<p>Ad una ad una fatevi aiutare dai pi\u00f9 piccoli con la fantasia per decorarle, mettendo uno strato di cioccolato dove preferite e applicate gli zuccherini colorati!<\/p>\n<p>Vedrete che oltre ad avere la cucina piena di zuccherini, avrete realizzato anche delle bellissime e coloratissime <strong>Maschere di Carnevale di Pasta Frolla!<br \/>\n<\/strong><\/p>\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t<\/div>\r\n\t\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1788 size-large\" src=\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-al-farro-1024x683.jpg\" alt=\"Maschere di pasta frolla\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-al-farro-1024x683.jpg 1024w, https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-al-farro-300x200.jpg 300w, https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-al-farro-768x512.jpg 768w, https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-al-farro-1170x780.jpg 1170w, https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-al-farro-585x390.jpg 585w, https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-al-farro.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Per la preparazione di queste maschere di pasta frolla abbiamo utilizzato esclusivamente prodotti di qualit\u00e0 come:<br \/>\n&#8211; <a href=\"https:\/\/www.shopiemonte.com\/farina-di-grano-tenero-tipo-1-per-frolla-1-kg\" target=\"_blank\" rel=\"noopener\">Farina di Grano Tenero Tipo 1 per Frolla 1 kg<\/a>\u00a0&#8211; Farina Viva;<br \/>\n&#8211; <a href=\"https:\/\/www.shopiemonte.com\/tavoletta-al-latte-finissimo\" target=\"_blank\" rel=\"noopener\">Tavoletta al Latte Finissimo<\/a> &#8211; Baratti&amp;Milano;<\/p>\n<p>In alternativa potete smezzare la quantit\u00e0 di farina per Pasta Frolla con della <a href=\"https:\/\/www.shopiemonte.com\/farina-di-farro-monococco-integrale-1-kg\" target=\"_blank\" rel=\"noopener\">Farina di Farro Monococco Integrale 1 kg<\/a>, sempre di Farina Viva,\u00a0\u00a0per renderle pi\u00f9 integrali.<\/p>\n<p>Per accompagnare la merenda dei pi\u00f9 piccoli, cosa c&#8217;\u00e8 di meglio di un buon <strong><a href=\"https:\/\/www.shopiemonte.com\/succhi-di-frutta\" target=\"_blank\" rel=\"noopener\">succo di frutta<\/a><\/strong>? Albicocca, pesca, mela, pera&#8230; ma anche cocktail di frutta &amp; vedura super vitaminici&#8230; e con la garanzia di bere solo 100% frutta fresca!<\/p>\n<p>Buon divertimento! Aspettiamo le foto delle vostre creazioni sui nostri social: condivi le tue mascherine su <a href=\"https:\/\/www.facebook.com\/Shopiemonte\" target=\"_blank\" rel=\"noopener\">Facebook<\/a> e <a href=\"https:\/\/www.instagram.com\/shopiemonte.com_\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a>, taggando Shop Piemonte!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Carnevale si preparano maschere di ogni tipo, anche di Pasta Frolla! Ecco la ricetta da fare con i vostri bambini.<\/p>\n","protected":false},"author":1,"featured_media":1770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[45,44],"class_list":["post-1769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ricette-piemontesi","tag-cucina-piemontese","tag-ricette-piemontesi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maschere di Carnevale di Pasta Frolla - Il Magazine di Shopiemonte<\/title>\n<meta name=\"description\" content=\"Ecco le Maschere di Carnevale di Pasta Frolla: un&#039;idea originale per grandi e piccini che amano i dolci, da cucinare insieme!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maschere di Carnevale di Pasta Frolla - Il Magazine di Shopiemonte\" \/>\n<meta property=\"og:description\" content=\"Ecco le Maschere di Carnevale di Pasta Frolla: un&#039;idea originale per grandi e piccini che amano i dolci, da cucinare insieme!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla\" \/>\n<meta property=\"og:site_name\" content=\"Il Magazine di Shopiemonte\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-09T13:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-11T11:13:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-pasta-frolla.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shop Piemonte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shop Piemonte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla\",\"url\":\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla\",\"name\":\"Maschere di Carnevale di Pasta Frolla - Il Magazine di Shopiemonte\",\"isPartOf\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-pasta-frolla.jpg\",\"datePublished\":\"2022-02-09T13:59:00+00:00\",\"dateModified\":\"2022-02-11T11:13:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/c1c9385f909b5091b0f3d4948988e7cb\"},\"description\":\"Ecco le Maschere di Carnevale di Pasta Frolla: un'idea originale per grandi e piccini che amano i dolci, da cucinare insieme!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#primaryimage\",\"url\":\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-pasta-frolla.jpg\",\"contentUrl\":\"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-pasta-frolla.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Maschere di Carnevale di Pasta Frolla\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.shopiemonte.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricette Piemontesi\",\"item\":\"https:\/\/www.shopiemonte.com\/blog\/category\/ricette-piemontesi\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maschere di Carnevale di Pasta Frolla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#website\",\"url\":\"https:\/\/www.shopiemonte.com\/blog\/\",\"name\":\"Il Magazine di Shopiemonte\",\"description\":\"ricette e curiosit\u00e0 dal Piemonte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.shopiemonte.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/c1c9385f909b5091b0f3d4948988e7cb\",\"name\":\"Shop Piemonte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7dee0011d3baeae2ef5f0101daa8f40c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7dee0011d3baeae2ef5f0101daa8f40c?s=96&d=mm&r=g\",\"caption\":\"Shop Piemonte\"},\"url\":\"https:\/\/www.shopiemonte.com\/blog\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maschere di Carnevale di Pasta Frolla - Il Magazine di Shopiemonte","description":"Ecco le Maschere di Carnevale di Pasta Frolla: un'idea originale per grandi e piccini che amano i dolci, da cucinare insieme!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla","og_locale":"it_IT","og_type":"article","og_title":"Maschere di Carnevale di Pasta Frolla - Il Magazine di Shopiemonte","og_description":"Ecco le Maschere di Carnevale di Pasta Frolla: un'idea originale per grandi e piccini che amano i dolci, da cucinare insieme!","og_url":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla","og_site_name":"Il Magazine di Shopiemonte","article_published_time":"2022-02-09T13:59:00+00:00","article_modified_time":"2022-02-11T11:13:56+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-pasta-frolla.jpg","type":"image\/jpeg"}],"author":"Shop Piemonte","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Shop Piemonte","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla","url":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla","name":"Maschere di Carnevale di Pasta Frolla - Il Magazine di Shopiemonte","isPartOf":{"@id":"https:\/\/www.shopiemonte.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#primaryimage"},"image":{"@id":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#primaryimage"},"thumbnailUrl":"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-pasta-frolla.jpg","datePublished":"2022-02-09T13:59:00+00:00","dateModified":"2022-02-11T11:13:56+00:00","author":{"@id":"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/c1c9385f909b5091b0f3d4948988e7cb"},"description":"Ecco le Maschere di Carnevale di Pasta Frolla: un'idea originale per grandi e piccini che amano i dolci, da cucinare insieme!","breadcrumb":{"@id":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#primaryimage","url":"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-pasta-frolla.jpg","contentUrl":"https:\/\/www.shopiemonte.com\/blog\/wp-content\/uploads\/2018\/01\/Maschere-di-carnevale-pasta-frolla.jpg","width":1200,"height":800,"caption":"Maschere di Carnevale di Pasta Frolla"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shopiemonte.com\/blog\/ricette-piemontesi\/maschere-carnevale-pasta-frolla#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shopiemonte.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ricette Piemontesi","item":"https:\/\/www.shopiemonte.com\/blog\/category\/ricette-piemontesi"},{"@type":"ListItem","position":3,"name":"Maschere di Carnevale di Pasta Frolla"}]},{"@type":"WebSite","@id":"https:\/\/www.shopiemonte.com\/blog\/#website","url":"https:\/\/www.shopiemonte.com\/blog\/","name":"Il Magazine di Shopiemonte","description":"ricette e curiosit\u00e0 dal Piemonte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shopiemonte.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/c1c9385f909b5091b0f3d4948988e7cb","name":"Shop Piemonte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.shopiemonte.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7dee0011d3baeae2ef5f0101daa8f40c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7dee0011d3baeae2ef5f0101daa8f40c?s=96&d=mm&r=g","caption":"Shop Piemonte"},"url":"https:\/\/www.shopiemonte.com\/blog\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/posts\/1769"}],"collection":[{"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/comments?post=1769"}],"version-history":[{"count":8,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/posts\/1769\/revisions"}],"predecessor-version":[{"id":3849,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/posts\/1769\/revisions\/3849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/media\/1770"}],"wp:attachment":[{"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/media?parent=1769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/categories?post=1769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shopiemonte.com\/blog\/wp-json\/wp\/v2\/tags?post=1769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}